{"id":499,"date":"2015-03-19T17:58:30","date_gmt":"2015-03-19T17:58:30","guid":{"rendered":"http:\/\/fitness3.mythemecloud.io\/\/?page_id=2"},"modified":"2025-07-19T20:59:15","modified_gmt":"2025-07-19T18:59:15","slug":"accueil","status":"publish","type":"page","link":"https:\/\/apsam.bayiconseil.com\/en\/","title":{"rendered":"Accueil"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"499\" class=\"elementor elementor-499\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4302811 e-flex e-con-boxed e-con e-parent\" data-id=\"4302811\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cab2e8 elementor-widget elementor-widget-shortcode\" data-id=\"6cab2e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-176e264 elementor-widget elementor-widget-spacer\" data-id=\"176e264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa17dd0 e-flex e-con-boxed e-con e-parent\" data-id=\"aa17dd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f540e9 no-margin elementor-widget elementor-widget-heading\" data-id=\"9f540e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/apsam.bayiconseil.com\/en\/secteur-assurance\/\">Insurances<\/a><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ccb325 no-margin elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1ccb325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51e41e2 e-flex e-con-boxed e-con e-parent\" data-id=\"51e41e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f4102cf e-con-full e-flex e-con e-child\" data-id=\"f4102cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b131b08 elementor-widget elementor-widget-oew-blog-carousel\" data-id=\"b131b08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"oew-blog-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"oew-carousel oew-carousel-blog swiper-container-wrap clr\">\n\n\t\t\t\t<div class=\"swiper oew-carousel-container\" data-settings=\"{&quot;items&quot;:3,&quot;slides&quot;:3,&quot;margin&quot;:6,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:800,&quot;autoplay&quot;:2000,&quot;loop&quot;:&quot;1&quot;}\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-automobile\/\" title=\"Automobile Insurance\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"616\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Assurance Automobile\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-768x525.jpg 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161.jpg 1000w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-automobile\/\" title=\"Automobile Insurance\">Automobile Insurance<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tCar insurance is one of the most common forms of insurance in Mali. It\u2026\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-automobile\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-epargne\/\" title=\"Savings Insurance\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"616\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Assurance Epargne\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-768x525.jpg 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161.jpg 1000w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-epargne\/\" title=\"Savings Insurance\">Savings Insurance<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAssurance Epargne L\u2019assurance \u00e9pargne est un produit d\u2019assurance qui combine protection et constitution d\u2019un capital&hellip;\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-epargne\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-habitation\/\" title=\"Home Insurance\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"616\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Assurance Habitation\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-768x525.jpg 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161.jpg 1000w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-habitation\/\" title=\"Home Insurance\">Home Insurance<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAssurance Habitation L\u2019assurance habitation prot\u00e8ge un logement (maison ou appartement) ainsi que les biens qu\u2019il&hellip;\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-habitation\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-voyage\/\" title=\"Travel Insurance\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"616\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Assurance Voyage\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-768x525.jpg 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161.jpg 1000w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-voyage\/\" title=\"Travel Insurance\">Travel Insurance<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAssurance Voyage L\u2019assurance voyage couvre les impr\u00e9vus pouvant survenir avant ou pendant un d\u00e9placement \u00e0&hellip;\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-voyage\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-agricole\/\" title=\"Farm Insurance\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"616\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Assurance Agricole\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-768x525.jpg 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161.jpg 1000w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-agricole\/\" title=\"Farm Insurance\">Farm Insurance<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAssurance Agricole L\u2019assurance agricole est con\u00e7ue pour prot\u00e9ger les agriculteurs, \u00e9leveurs et exploitants contre les&hellip;\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-agricole\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-scolaire\/\" title=\"School Insurance\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"616\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Assurance Scolaire\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-768x525.jpg 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161.jpg 1000w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h6 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-scolaire\/\" title=\"School Insurance\">School Insurance<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tSchool insurance protects pupils and students against accidents that may occur at\u2026\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/assurance-scolaire\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div><!-- .oew-carousel -->\n\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd76236 e-flex e-con-boxed e-con e-parent\" data-id=\"cd76236\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ccb756 elementor-widget elementor-widget-spacer\" data-id=\"8ccb756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee38dd6 no-margin elementor-widget elementor-widget-heading\" data-id=\"ee38dd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">President's Word<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9b2deb no-margin elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b9b2deb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbbf285 e-flex e-con-boxed e-con e-parent\" data-id=\"cbbf285\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-976322f e-con-full e-flex e-con e-child\" data-id=\"976322f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4624054 elementor-widget elementor-widget-image\" data-id=\"4624054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Abdrahamane-KOUYATE.-President.jpg\" class=\"attachment-large size-large wp-image-2023\" alt=\"\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Abdrahamane-KOUYATE.-President.jpg 600w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Abdrahamane-KOUYATE.-President-300x300.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f834be oew-info-box-top elementor-widget elementor-widget-oew-info-box\" data-id=\"6f834be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;position&quot;:&quot;top&quot;}\" data-widget_type=\"oew-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"oew-info-box-wrap\">\n\t\t\t<div class=\"oew-info-box\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"oew-info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"oew-info-box-title\">\n\t\t\t\t\t\t\tAbdramane KOUYATE\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-info-box-description\">\n\t\t\t\t\t\t\tPresident\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21dbef8 elementor-widget elementor-widget-text-editor\" data-id=\"21dbef8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Abdrhamane KOUYATE is the General Director of the insurance company Sabunyuman. He was elected President of the association. He has been working in the insurance sector for over 20 years.<br \/>\u00a0It is for me a great honor and a particular responsibility to preside over the Professional Association of\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-093d67d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"093d67d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/apsam.bayiconseil.com\/en\/bureau\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-630908a e-con-full e-flex e-con e-child\" data-id=\"630908a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9119f3a elementor-widget elementor-widget-image\" data-id=\"9119f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/7586-600x600.jpg\" class=\"attachment-ocean-thumb-m size-ocean-thumb-m wp-image-1412\" alt=\"\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/7586-600x600.jpg 600w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/7586-300x300.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbd3d27 elementor-widget elementor-widget-heading\" data-id=\"cbd3d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Presentation of APSAM<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2124178 elementor-widget elementor-widget-text-editor\" data-id=\"2124178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Created on July 1, 1991, the Professional Association of Insurance Companies of Mali (APSAM) is the umbrella organization that brings together all insurance companies operating in Mali. Its main mission is to promote the insurance sector and defend the interests of its members.<br \/>APSAM is the expression of a unified voice for all insurance companies in Mali, regardless of their...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8f8ab9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c8f8ab9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/apsam.bayiconseil.com\/en\/qui-sommes-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2669bbe e-con-full e-flex e-con e-child\" data-id=\"2669bbe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd1c7e2 elementor-widget elementor-widget-image\" data-id=\"fd1c7e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Missions.png\" class=\"attachment-large size-large wp-image-1041\" alt=\"\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Missions.png 600w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Missions-300x300.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-256db8b elementor-widget elementor-widget-heading\" data-id=\"256db8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Our Missions<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-427fc5d elementor-widget elementor-widget-text-editor\" data-id=\"427fc5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>APSAM has assigned itself several missions summarized in seven:<\/p><ul><li>Representation of insurance companies<\/li><li>Insurance sector<\/li><li>Technical capacity building<\/li><li>Improvement of the regulatory framework<\/li><li>Development of cooperation<\/li><li>Business and technical intelligence<\/li><li>Participation in economic development<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-168d701 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"168d701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/apsam.bayiconseil.com\/en\/qui-sommes-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5aa3586 e-flex e-con-boxed e-con e-parent\" data-id=\"5aa3586\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92b1a5d elementor-widget elementor-widget-spacer\" data-id=\"92b1a5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8762cc no-margin elementor-widget elementor-widget-heading\" data-id=\"a8762cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">The Executive Board<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67f004b no-margin elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"67f004b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21ade09 e-flex e-con-boxed e-con e-parent\" data-id=\"21ade09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-be2242b e-con-full e-flex e-con e-child\" data-id=\"be2242b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e163fd elementor-widget elementor-widget-image\" data-id=\"8e163fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Abdrahamane-KOUYATE.-President.jpg\" class=\"attachment-ocean-thumb-m size-ocean-thumb-m wp-image-2023\" alt=\"\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Abdrahamane-KOUYATE.-President.jpg 600w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Abdrahamane-KOUYATE.-President-300x300.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0a7a5a oew-info-box-top elementor-widget elementor-widget-oew-info-box\" data-id=\"b0a7a5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;position&quot;:&quot;top&quot;}\" data-widget_type=\"oew-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"oew-info-box-wrap\">\n\t\t\t<div class=\"oew-info-box\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"oew-info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"oew-info-box-title\">\n\t\t\t\t\t\t\tAbdrahamane KOUYATE\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-info-box-description\">\n\t\t\t\t\t\t\tPresident\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-031f77b e-con-full e-flex e-con e-child\" data-id=\"031f77b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5fd5623 e-grid e-con-full e-con e-child\" data-id=\"5fd5623\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b1ac9f elementor-widget elementor-widget-oew-member\" data-id=\"4b1ac9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"oew-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"oew-member-wrap\">\n\n\t\t\t\t\t\t\t<div class=\"oew-member-image\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/300x300-pixels-DG-AFG.png\" title=\"Cisse Adam Ba\" alt=\"Cisse Adam Ba\" loading=\"lazy\" \/>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<div class=\"oew-member-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"oew-member-name\">\n\t\t\t\t\t\tCISSE Adam BA\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"oew-member-role\">Vice President<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"oew-member-icons\">\n\t\t\t\t\n\t\t\t\t\t<a href=\"#\" class=\"oew-member-icon elementor-repeater-item-2fe3267\" target=\"_blank\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff56bb8 elementor-widget elementor-widget-oew-member\" data-id=\"ff56bb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"oew-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"oew-member-wrap\">\n\n\t\t\t\t\t\t\t<div class=\"oew-member-image\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Karim-SANOGO-2emr-vice-president-en-charge-de-la-non-vie.jpg\" title=\"Karim SANOGO 2e\u0300mr vice pre\u0301sident en charge de la non vie\" alt=\"Karim SANOGO 2e\u0300mr vice pre\u0301sident en charge de la non vie\" loading=\"lazy\" \/>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<div class=\"oew-member-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"oew-member-name\">\n\t\t\t\t\t\tKarim SANOGO\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"oew-member-role\">2nd Vice-President of the Non-Life <\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"oew-member-icons\">\n\t\t\t\t\n\t\t\t\t\t<a href=\"#\" class=\"oew-member-icon elementor-repeater-item-539de5a oew-member-tooltip oew-tooltip-top\" title=\"Linkedin\" data-tooltip-position=\"top\" target=\"_blank\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d324a elementor-widget elementor-widget-oew-member\" data-id=\"24d324a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"oew-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"oew-member-wrap\">\n\n\t\t\t\t\t\t\t<div class=\"oew-member-image\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Corneille-SANON-2eme-Vice-President-en-charge-de-la-Vie.jpg\" title=\"Corneille SANON 2e\u0300me Vice Pre\u0301sident en charge de la Vie\" alt=\"Corneille SANON 2e\u0300me Vice Pre\u0301sident en charge de la Vie\" loading=\"lazy\" \/>\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<div class=\"oew-member-content\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"oew-member-name\">\n\t\t\t\t\t\tCorneille SANON\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"oew-member-role\">2nd Vice-President of the Life<\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"oew-member-icons\">\n\t\t\t\t\n\t\t\t\t\t<a href=\"#\" class=\"oew-member-icon elementor-repeater-item-539de5a oew-member-tooltip oew-tooltip-top\" title=\"Linkedin\" data-tooltip-position=\"top\" target=\"_blank\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c0d0b8 e-con-full e-flex e-con e-child\" data-id=\"5c0d0b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-137d8af elementor-widget elementor-widget-text-editor\" data-id=\"137d8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Since December 2020, the APSAM has been located in its own premises at\u00a0<i>la Maison de l\u2019Assurance\u00a0<\/i>\u00bb.<br \/><br \/>The governance of the APSAM is based on 4 bodies:<\/p><ul><li>The General Assembly<\/li><li>Board<\/li><li>An Executive Secretariat<\/li><li>Technical committees<\/li><\/ul><p>Board of <b>5 members<\/b> It is composed of a President, 3 Vice-Presidents and a General Treasurer. The term of office of the Bureau is 2 years, renewable.<br \/><br \/>The Board has the broadest powers for the administration and management of APSAM's affairs as well as for the execution of the decisions of the GMs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aceb85 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9aceb85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/apsam.bayiconseil.com\/en\/bureau\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6e47ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6e47ed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-633642e\" data-id=\"633642e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1c2e0e no-margin elementor-widget elementor-widget-heading\" data-id=\"f1c2e0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Action plans and several initiatives to its credit!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c5a51ce e-flex e-con-boxed e-con e-parent\" data-id=\"c5a51ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a054c4 elementor-widget elementor-widget-spacer\" data-id=\"3a054c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1b51ed no-margin elementor-widget elementor-widget-heading\" data-id=\"b1b51ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Some key figures<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff0e892 no-margin elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ff0e892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2339350 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2339350\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df3927e\" data-id=\"df3927e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3fa4049 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fa4049\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7360fde\" data-id=\"7360fde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24fda7d no-margin elementor-widget elementor-widget-counter\" data-id=\"24fda7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Insurance companies<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"13\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de54af1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"de54af1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff85546 no-margin elementor-widget elementor-widget-counter\" data-id=\"ff85546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Years of Experience<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"28\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-adbbb5c\" data-id=\"adbbb5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9243fd no-margin elementor-widget elementor-widget-counter\" data-id=\"e9243fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Jobs generated<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1500\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5dd58b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c5dd58b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b42cf9d no-margin elementor-widget elementor-widget-counter\" data-id=\"b42cf9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Funds paid to beneficiaries<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"20\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-24e28e3 e-flex e-con-boxed e-con e-parent\" data-id=\"24e28e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fb2db no-margin elementor-widget elementor-widget-heading\" data-id=\"77fb2db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Our partners<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6587186 no-margin elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6587186\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09b93e7 e-flex e-con-boxed e-con e-parent\" data-id=\"09b93e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfcf223 elementor-widget elementor-widget-image-carousel\" data-id=\"dfcf223\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1000,&quot;speed&quot;:1000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Ministere-eco-finance-1.png\" alt=\"Minist\u00e8re de l&#039;Economie et de la Finance\" \/><figcaption class=\"elementor-image-carousel-caption\">Minist\u00e8re de l'Economie et de la Finance<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/CIMA-1.png\" alt=\"CIMA\" \/><figcaption class=\"elementor-image-carousel-caption\">CIMA<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Pool-1.png\" alt=\"Pool TPV\" \/><figcaption class=\"elementor-image-carousel-caption\">Pool TPV<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Fanaf-logo-1.png\" alt=\"FANAF\" \/><figcaption class=\"elementor-image-carousel-caption\">FANAF<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/CNPM-logo-1.png\" alt=\"CNPM\" \/><figcaption class=\"elementor-image-carousel-caption\">CNPM<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/CESC.png\" alt=\"CECS\" \/><figcaption class=\"elementor-image-carousel-caption\">CESC<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/OAA-logo-1.png\" alt=\"OAA\" \/><figcaption class=\"elementor-image-carousel-caption\">OAA<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/ANASER.png\" alt=\"ANASER\" \/><figcaption class=\"elementor-image-carousel-caption\">ANASER<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Ministere-des-Transports-et-des-Infrastructures.png\" alt=\"Minist\u00e8re des Transports et des Infrastructures\" \/><figcaption class=\"elementor-image-carousel-caption\">Minist\u00e8re des Transports et des Infrastructures<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Police-Nationale.png\" alt=\"Police Nationale\" \/><figcaption class=\"elementor-image-carousel-caption\">Police Nationale<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aebf899 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aebf899\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-377d82a\" data-id=\"377d82a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d712c4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d712c4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-819a9dc\" data-id=\"819a9dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-672e4c9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"672e4c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cebe703\" data-id=\"cebe703\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cc2f4e elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"0cc2f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTell me what you need!\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWe will respond to you\ud83d\udc4d\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73c7b5b\" data-id=\"73c7b5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3164f4 elementor-align-center elementor-widget elementor-widget-oew-newsletter\" data-id=\"b3164f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;hide_button_label&quot;:&quot;no&quot;,&quot;add_icon&quot;:&quot;no&quot;}\" data-widget_type=\"oew-newsletter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"oew-newsletter-form clr\">\n\n\t\t\t<div id=\"mc_embed_signup\" class=\"oew-newsletter-form-wrap\">\n\n\t\t\t\t<form action=\"\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" novalidate data-trp-original-action=\"\">\n\n\t\t\t\t\t<div class=\"email-wrap elem-wrap\">\n\t\t\t\t\t\t<input aria-label=\"Enter your email address to subscribe\" type=\"email\" value=\"Recevoir notre newsletter\" onfocus=\"if (this.value == this.defaultValue)this.value = '';\" onblur=\"if (this.value == '')this.value = this.defaultValue;\" name=\"EMAIL\" class=\"required email\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<button aria-label=\"Submit email address\" type=\"submit\" value=\"\" name=\"subscribe\" class=\"oew-newsletter-form-button button\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Send<span>\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"email-err err-msg req\" style=\"display:none;\">Email is required<\/span>\n\t\t\t\t\t<span class=\"email-err err-msg not-valid\" style=\"display:none;\">Email is not valid<\/span>\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"success res-msg\" style=\"display:none;\">Thanks for your subscription.<\/div>\n\t\t\t\t\t<div class=\"failed  res-msg\" style=\"display:none;\">Failed to subscribe, please contact admin.<\/div>\n\t\t\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\n\t\t\t<\/div><!--.oew-newsletter-form-wrap-->\n\n\t\t<\/div><!-- .oew-newsletter-form -->\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-532eb5f e-flex e-con-boxed e-con e-parent\" data-id=\"532eb5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c9cd3 elementor-widget elementor-widget-spacer\" data-id=\"c5c9cd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66c9024 e-flex e-con-boxed e-con e-parent\" data-id=\"66c9024\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ceda618 no-margin elementor-widget elementor-widget-heading\" data-id=\"ceda618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">News<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb95b6c no-margin elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cb95b6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b55c013 elementor-widget elementor-widget-text-editor\" data-id=\"b55c013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Discover all the news of the association.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b94ad96 e-flex e-con-boxed e-con e-parent\" data-id=\"b94ad96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0b94486 e-con-full e-flex e-con e-child\" data-id=\"0b94486\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a0de90 elementor-widget elementor-widget-oew-blog-carousel\" data-id=\"7a0de90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"oew-blog-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"oew-carousel oew-carousel-blog swiper-container-wrap clr\">\n\n\t\t\t\t<div class=\"swiper oew-carousel-container has-dots\" data-settings=\"{&quot;items&quot;:3,&quot;slides&quot;:1,&quot;margin&quot;:10,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:400,&quot;autoplay&quot;:3000,&quot;loop&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;1&quot;,&quot;dots&quot;:&quot;1&quot;}\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/atelier-de-renforcement-des-capacites-des-magistrats-sur-le-code-cima\/\" title=\"Capacity building workshop for magistrates on the CIMA code\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"625\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Magistrat-CIMA-900x625.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Atelier de renforcement des capacit\u00e9s des magistrats sur le code CIMA\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Magistrat-CIMA-900x625.png 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Magistrat-CIMA-768x533.png 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Magistrat-CIMA.png 1080w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/atelier-de-renforcement-des-capacites-des-magistrats-sur-le-code-cima\/\" title=\"Capacity building workshop for magistrates on the CIMA code\">Capacity building workshop for magistrates on the CIMA code<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tCapacity building workshop for magistrates on the CIMA code\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/atelier-de-renforcement-des-capacites-des-magistrats-sur-le-code-cima\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/voyage-dimmersion-et-de-benchmarking-a-lasaci\/\" title=\"Immersion and Benchmarking Trip to ASACI\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"625\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Visite-Asaci-900x625.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Voyage d\u2019immersion et de Benchmarking \u00e0 l\u2019ASACI\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Visite-Asaci-900x625.png 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Visite-Asaci-768x533.png 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Visite-Asaci.png 1080w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/voyage-dimmersion-et-de-benchmarking-a-lasaci\/\" title=\"Immersion and Benchmarking Trip to ASACI\">Immersion and Benchmarking Trip to ASACI<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tImmersion and Benchmarking trip of the Secretary General of the Committee of Insurance Companies of Mali\u2026\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/voyage-dimmersion-et-de-benchmarking-a-lasaci\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/tournoi-de-football-coupe-corpo-des-assurances-2eme-edition\/\" title=\"Football Tournament - Corporate Cup of Insurances 2nd edition\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"625\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Foot-Article-900x625.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Tournoi de Football \u2013 Coupe Corpo des Assurances 2\u00e8me \u00e9dition\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Foot-Article-900x625.png 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Foot-Article-768x533.png 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Foot-Article.png 1080w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/tournoi-de-football-coupe-corpo-des-assurances-2eme-edition\/\" title=\"Football Tournament - Corporate Cup of Insurances 2nd edition\">Football Tournament - Corporate Cup of Insurances 2nd edition<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tThe Committee of Insurance Companies of Mali (CCAM) brilliantly organized the 2nd edition\u2026\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/tournoi-de-football-coupe-corpo-des-assurances-2eme-edition\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/seminaire-de-formation-sur-le-controle-fiscal\/\" title=\"Training seminar on tax auditing\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"625\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Seminaire-900x625.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"S\u00e9minaire de formation sur le contr\u00f4le fiscal\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Seminaire-900x625.png 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Seminaire-768x533.png 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Article-Seminaire.png 1080w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/seminaire-de-formation-sur-le-controle-fiscal\/\" title=\"Training seminar on tax auditing\">Training seminar on tax auditing<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\"The Committee of Insurance Companies of Mali (CCAM) organized a training seminar on\u2026\"\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/seminaire-de-formation-sur-le-controle-fiscal\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/formation-sur-la-maitrise-des-risques-dentreprises\/\" title=\"Training on Enterprise Risk Management\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"625\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Seminaire-900x625.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Formation sur la ma\u00eetrise des risques d\u2019entreprises\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Seminaire-900x625.png 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Seminaire-768x533.png 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Seminaire.png 1080w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/formation-sur-la-maitrise-des-risques-dentreprises\/\" title=\"Training on Enterprise Risk Management\">Training on Enterprise Risk Management<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tThe Committee of Insurance Companies of Mali is strengthening the capacities of its members in...\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/formation-sur-la-maitrise-des-risques-dentreprises\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"oew-carousel-slide swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-media clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/reunion-ordinaire-du-bureau-du-comite-des-compagnies-dassurances-du-mali\/\" title=\"Ordinary meeting of the Bureau of the Committee of Insurance Companies of Mali: A resounding success!\" class=\"oew-carousel-entry-img\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"625\" src=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Bureau-900x625.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"R\u00e9union ordinaire du Bureau du Comit\u00e9 des Compagnies d\u2019Assurances du Mali : Un franc succ\u00e8s !\" itemprop=\"image\" srcset=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Bureau-900x625.png 900w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Bureau-768x533.png 768w, https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/Bureau.png 1080w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-media -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-details clr\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"oew-carousel-entry-title entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/reunion-ordinaire-du-bureau-du-comite-des-compagnies-dassurances-du-mali\/\" title=\"Ordinary meeting of the Bureau of the Committee of Insurance Companies of Mali: A resounding success!\">Ordinary meeting of the Bureau of the Committee of Insurance Companies of Mali: A resounding success!<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"meta\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-excerpt clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tThe Office of the Committee of Insurance Companies of Mali (CCAM) held its ordinary meeting\u2026\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"oew-carousel-entry-readmore readmore-btn clr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apsam.bayiconseil.com\/en\/reunion-ordinaire-du-bureau-du-comite-des-compagnies-dassurances-du-mali\/\">More<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-excerpt -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- .oew-carousel-entry-details -->\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-button-next oew-swiper-buttons swiper-button-next-7a0de90\">\n\t\t\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 512.002 512.002\" xml:space=\"preserve\"><path d=\"M388.425,241.951L151.609,5.79c-7.759-7.733-20.321-7.72-28.067,0.04c-7.74,7.759-7.72,20.328,0.04,28.067l222.72,222.105L123.574,478.106c-7.759,7.74-7.779,20.301-0.04,28.061c3.883,3.89,8.97,5.835,14.057,5.835c5.074,0,10.141-1.932,14.017-5.795l236.817-236.155c3.737-3.718,5.834-8.778,5.834-14.05S392.156,245.676,388.425,241.951z\"\/><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev oew-swiper-buttons swiper-button-prev-7a0de90\">\n\t\t\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 443.52 443.52\" xml:space=\"preserve\"><path d=\"M143.492,221.863L336.226,29.129c6.663-6.664,6.663-17.468,0-24.132c-6.665-6.662-17.468-6.662-24.132,0l-204.8,204.8c-6.662,6.664-6.662,17.468,0,24.132l204.8,204.8c6.78,6.548,17.584,6.36,24.132-0.42c6.387-6.614,6.387-17.099,0-23.712L143.492,221.863z\"\/><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination swiper-pagination-7a0de90\"><\/div>\n\t\t\t\t\t\n\t\t\t<\/div><!-- .oew-carousel -->\n\n\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9db4ec0 elementor-widget elementor-widget-spacer\" data-id=\"9db4ec0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>nos assurances Assurance Automobile Assurance Automobile L\u2019assurance automobile est l\u2019une des formes d\u2019assurance les plus courantes au Mali. Elle\u2026 En savoir plus Assurance Transport Assurance Transport L\u2019assurance transport couvre les marchandises ou v\u00e9hicules contre les risques de perte, de\u2026 En savoir plus Assurance Incendie et Risques Divers (IRDS) Assurance Incendie et Risques Divers (IRDS) L\u2019assurance [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"on","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ofc_meta_disable_footer_callout":"","ofc_meta_callout_button_url":"","ofc_meta_callout_button_txt":"","ofc_meta_callout_text":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"class_list":["post-499","page","type-page","status-publish","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueil - APSAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apsam.bayiconseil.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueil - APSAM\" \/>\n<meta property=\"og:description\" content=\"nos assurances Assurance Automobile Assurance Automobile L\u2019assurance automobile est l\u2019une des formes d\u2019assurance les plus courantes au Mali. Elle\u2026 En savoir plus Assurance Transport Assurance Transport L\u2019assurance transport couvre les marchandises ou v\u00e9hicules contre les risques de perte, de\u2026 En savoir plus Assurance Incendie et Risques Divers (IRDS) Assurance Incendie et Risques Divers (IRDS) L\u2019assurance [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apsam.bayiconseil.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"APSAM\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-19T18:59:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/\",\"url\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/\",\"name\":\"Accueil - APSAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2151924161-900x616.jpg\",\"datePublished\":\"2015-03-19T17:58:30+00:00\",\"dateModified\":\"2025-07-19T18:59:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apsam.bayiconseil.com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2151924161-900x616.jpg\",\"contentUrl\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2151924161-900x616.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#website\",\"url\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/\",\"name\":\"APSAM\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#organization\",\"name\":\"APSAM\",\"url\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image001-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/image001-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"APSAM\"},\"image\":{\"@id\":\"https:\\\/\\\/apsam.bayiconseil.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - APSAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apsam.bayiconseil.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Accueil - APSAM","og_description":"nos assurances Assurance Automobile Assurance Automobile L\u2019assurance automobile est l\u2019une des formes d\u2019assurance les plus courantes au Mali. Elle\u2026 En savoir plus Assurance Transport Assurance Transport L\u2019assurance transport couvre les marchandises ou v\u00e9hicules contre les risques de perte, de\u2026 En savoir plus Assurance Incendie et Risques Divers (IRDS) Assurance Incendie et Risques Divers (IRDS) L\u2019assurance [&hellip;]","og_url":"https:\/\/apsam.bayiconseil.com\/en\/","og_site_name":"APSAM","article_modified_time":"2025-07-19T18:59:15+00:00","og_image":[{"url":"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apsam.bayiconseil.com\/","url":"https:\/\/apsam.bayiconseil.com\/","name":"Accueil - APSAM","isPartOf":{"@id":"https:\/\/apsam.bayiconseil.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apsam.bayiconseil.com\/#primaryimage"},"image":{"@id":"https:\/\/apsam.bayiconseil.com\/#primaryimage"},"thumbnailUrl":"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg","datePublished":"2015-03-19T17:58:30+00:00","dateModified":"2025-07-19T18:59:15+00:00","breadcrumb":{"@id":"https:\/\/apsam.bayiconseil.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apsam.bayiconseil.com\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apsam.bayiconseil.com\/#primaryimage","url":"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg","contentUrl":"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/2151924161-900x616.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/apsam.bayiconseil.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/apsam.bayiconseil.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/apsam.bayiconseil.com\/#website","url":"https:\/\/apsam.bayiconseil.com\/","name":"APSAM","description":"","publisher":{"@id":"https:\/\/apsam.bayiconseil.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apsam.bayiconseil.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/apsam.bayiconseil.com\/#organization","name":"APSAM","url":"https:\/\/apsam.bayiconseil.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apsam.bayiconseil.com\/#\/schema\/logo\/image\/","url":"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/image001-scaled.jpg","contentUrl":"https:\/\/apsam.bayiconseil.com\/wp-content\/uploads\/2025\/07\/image001-scaled.jpg","width":2560,"height":1706,"caption":"APSAM"},"image":{"@id":"https:\/\/apsam.bayiconseil.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/pages\/499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":443,"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/pages\/499\/revisions"}],"predecessor-version":[{"id":2206,"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/pages\/499\/revisions\/2206"}],"wp:attachment":[{"href":"https:\/\/apsam.bayiconseil.com\/en\/wp-json\/wp\/v2\/media?parent=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}